{"id":126,"count":2,"description":"","link":"https:\/\/asbizempire.com\/lt\/category\/verslo-planai\/","name":"Verslo planai","slug":"verslo-planai","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/asbizempire.com\/lt\/category\/verslo-planai\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"lt_LT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Business Solutions -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Verslo planai - Business Solutions\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/asbizempire.com\/lt\/category\/verslo-planai\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/asbizempire.com\/wp-content\/uploads\/2024\/07\/Founder-Ausra.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/asbizempire.com\/wp-content\/uploads\/2024\/07\/Founder-Ausra.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"683\" \/>\n\t\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ASBizEmpire\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Verslo planai - Business Solutions\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/asbizempire.com\/wp-content\/uploads\/2024\/07\/Founder-Ausra.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/126\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/category\\\/verslo-planai\\\/#listItem\",\"name\":\"Verslo planai\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/category\\\/verslo-planai\\\/#listItem\",\"position\":2,\"name\":\"Verslo planai\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/126\\\/#collectionpage\",\"url\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/126\\\/\",\"name\":\"Verslo planai - Business Solutions\",\"inLanguage\":\"lt-LT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/126\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/#organization\",\"name\":\"asbizempire.com\",\"url\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/\",\"telephone\":\"+441883818360\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/asbizempire.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/logo_d.svg\",\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/126\\\/#organizationLogo\",\"width\":986,\"height\":221},\"image\":{\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/126\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ASBizEmpire\",\"https:\\\/\\\/www.instagram.com\\\/as_biz_empire\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/#website\",\"url\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/\",\"name\":\"asbizempire.com\",\"inLanguage\":\"lt-LT\",\"publisher\":{\"@id\":\"https:\\\/\\\/asbizempire.com\\\/lt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Verslo planai - Business Solutions<\/title>\n\n","aioseo_head_json":{"title":"Verslo planai - Business Solutions","description":"","canonical_url":"https:\/\/asbizempire.com\/lt\/category\/verslo-planai\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/asbizempire.com\/lt\/wp-json\/wp\/v2\/categories\/126\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/asbizempire.com\/lt\/#listItem","position":1,"name":"Home","item":"https:\/\/asbizempire.com\/lt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/asbizempire.com\/lt\/category\/verslo-planai\/#listItem","name":"Verslo planai"}},{"@type":"ListItem","@id":"https:\/\/asbizempire.com\/lt\/category\/verslo-planai\/#listItem","position":2,"name":"Verslo planai","previousItem":{"@type":"ListItem","@id":"https:\/\/asbizempire.com\/lt\/#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/asbizempire.com\/lt\/wp-json\/wp\/v2\/categories\/126\/#collectionpage","url":"https:\/\/asbizempire.com\/lt\/wp-json\/wp\/v2\/categories\/126\/","name":"Verslo planai - Business Solutions","inLanguage":"lt-LT","isPartOf":{"@id":"https:\/\/asbizempire.com\/lt\/#website"},"breadcrumb":{"@id":"https:\/\/asbizempire.com\/lt\/wp-json\/wp\/v2\/categories\/126\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/asbizempire.com\/lt\/#organization","name":"asbizempire.com","url":"https:\/\/asbizempire.com\/lt\/","telephone":"+441883818360","logo":{"@type":"ImageObject","url":"https:\/\/asbizempire.com\/wp-content\/uploads\/2022\/11\/logo_d.svg","@id":"https:\/\/asbizempire.com\/lt\/wp-json\/wp\/v2\/categories\/126\/#organizationLogo","width":986,"height":221},"image":{"@id":"https:\/\/asbizempire.com\/lt\/wp-json\/wp\/v2\/categories\/126\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/ASBizEmpire","https:\/\/www.instagram.com\/as_biz_empire\/"]},{"@type":"WebSite","@id":"https:\/\/asbizempire.com\/lt\/#website","url":"https:\/\/asbizempire.com\/lt\/","name":"asbizempire.com","inLanguage":"lt-LT","publisher":{"@id":"https:\/\/asbizempire.com\/lt\/#organization"}}]},"og:locale":"lt_LT","og:site_name":"Business Solutions -","og:type":"article","og:title":"Verslo planai - Business Solutions","og:url":"https:\/\/asbizempire.com\/lt\/category\/verslo-planai\/","og:image":"https:\/\/asbizempire.com\/wp-content\/uploads\/2024\/07\/Founder-Ausra.jpg","og:image:secure_url":"https:\/\/asbizempire.com\/wp-content\/uploads\/2024\/07\/Founder-Ausra.jpg","og:image:width":683,"og:image:height":683,"article:publisher":"https:\/\/www.facebook.com\/ASBizEmpire","twitter:card":"summary_large_image","twitter:title":"Verslo planai - Business Solutions","twitter:image":"https:\/\/asbizempire.com\/wp-content\/uploads\/2024\/07\/Founder-Ausra.jpg"},"aioseo_meta_data":{"term_id":"126","title":null,"description":null,"keywords":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"pillar_content":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"tabs":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 22:48:21","breadcrumb_settings":null,"created":"2025-08-14 20:08:20","updated":"2026-05-12 22:48:21","og_image_url":null,"og_image_width":null,"og_image_height":null,"twitter_image_url":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/asbizempire.com\/lt\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tVerslo planai\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/asbizempire.com\/lt\/"},{"label":"Verslo planai","link":"https:\/\/asbizempire.com\/lt\/category\/verslo-planai\/"}],"_links":{"self":[{"href":"https:\/\/asbizempire.com\/lt\/wp-json\/wp\/v2\/categories\/126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asbizempire.com\/lt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/asbizempire.com\/lt\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/asbizempire.com\/lt\/wp-json\/wp\/v2\/posts?categories=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}